{"id":141192,"date":"2026-07-15T15:15:19","date_gmt":"2026-07-15T21:15:19","guid":{"rendered":"https:\/\/mexpress.info\/index\/?p=141192"},"modified":"2026-07-15T15:15:19","modified_gmt":"2026-07-15T21:15:19","slug":"manuel-guerra-cavazos-blinda-garcia-con-nuevo-arco-carretero-inteligente-fortalece-escudo-garcia-y-consolida-historica-baja-en-delitos","status":"publish","type":"post","link":"https:\/\/mexpress.info\/index\/2026\/07\/manuel-guerra-cavazos-blinda-garcia-con-nuevo-arco-carretero-inteligente-fortalece-escudo-garcia-y-consolida-historica-baja-en-delitos\/","title":{"rendered":"MANUEL GUERRA CAVAZOS BLINDA GARC\u00cdA CON NUEVO ARCO CARRETERO INTELIGENTE; FORTALECE &#8220;ESCUDO GARC\u00cdA&#8221; Y CONSOLIDA HIST\u00d3RICA BAJA EN DELITOS"},"content":{"rendered":"<p>Conectado al C4 Inteligente, el nuevo sistema fortalece la vigilancia, el control vehicular y la capacidad de respuesta; el municipio pas\u00f3 de registrar hasta 25 homicidios mensuales en 2024 a cero durante junio de 2026.<\/p>\n<p>Garc\u00eda, Nuevo Le\u00f3n.\u2013 Como parte del fortalecimiento de la estrategia integral de seguridad &#8220;Escudo Garc\u00eda&#8221;, el alcalde Manuel Guerra Cavazos puso en operaci\u00f3n el nuevo Arco Carretero Inteligente, conectado al C4 Inteligente, sobre la avenida Lincoln, en las inmediaciones del l\u00edmite con Monterrey, con el objetivo de reforzar la vigilancia, el control vehicular, la prevenci\u00f3n del delito y la capacidad de respuesta de las corporaciones de seguridad.<\/p>\n<p>Durante la inauguraci\u00f3n, el presidente municipal destac\u00f3 que la inversi\u00f3n en tecnolog\u00eda e inteligencia ha permitido consolidar una estrategia moderna que hoy se traduce en resultados hist\u00f3ricos para la seguridad de las familias de Garc\u00eda.<\/p>\n<p>&#8220;Este Arco Carretero Inteligente forma parte de la estrategia que hemos venido implementando para optimizar las herramientas tecnol\u00f3gicas con las que cuenta nuestra ciudad&#8221;, expres\u00f3.<\/p>\n<p>Record\u00f3 que desde el inicio de su administraci\u00f3n se plante\u00f3 la creaci\u00f3n de un sistema integral de inteligencia que permitiera fortalecer la capacidad operativa del municipio.<\/p>\n<p>&#8220;Desde el primer minuto de nuestro gobierno nos propusimos construir un cerebro tecnol\u00f3gico que nos permitiera analizar informaci\u00f3n en tiempo real. As\u00ed naci\u00f3 el C4 Inteligente; posteriormente creamos las Unidades de Vigilancia Inteligente (UVIS), que diariamente recorren la ciudad recopilando informaci\u00f3n estrat\u00e9gica para localizar objetivos prioritarios, y m\u00e1s adelante instalamos las Estaciones de Vigilancia Inteligente distribuidas en distintos sectores del municipio&#8221;, se\u00f1al\u00f3.<\/p>\n<p>El alcalde explic\u00f3 que, adem\u00e1s de ampliar la infraestructura tecnol\u00f3gica, su administraci\u00f3n moderniz\u00f3 por completo el sistema de videovigilancia.<\/p>\n<p>&#8220;Los gobiernos anteriores no apostaban por la tecnolog\u00eda. Recibimos un sistema obsoleto, con apenas cuatro pantallas y c\u00e1maras de primera generaci\u00f3n que ya no serv\u00edan. Hoy contamos con una red moderna que permite lectura de placas, an\u00e1lisis de pol\u00edgonos, reconocimiento facial e inteligencia artificial para fortalecer las tareas de seguridad&#8221;, subray\u00f3.<\/p>\n<p>Guerra Cavazos aclar\u00f3 que el nuevo Arco Carretero Inteligente no tendr\u00e1 fines recaudatorios ni ser\u00e1 utilizado para aplicar multas de tr\u00e1nsito.<\/p>\n<p>&#8220;Quiero dejar muy claro que este arco no es para infraccionar ni para generar sanciones de movilidad. Su prop\u00f3sito es brindar inteligencia, datos y precisi\u00f3n para fortalecer el cerco de seguridad de nuestro municipio y seguir consolidando el Escudo Garc\u00eda&#8221;, enfatiz\u00f3.<\/p>\n<p>A\u00f1adi\u00f3 que el sistema cuenta con tecnolog\u00eda de \u00faltima generaci\u00f3n que permite identificar, en tiempo real, veh\u00edculos y personas relacionadas con objetivos prioritarios, facilitando una reacci\u00f3n inmediata por parte de las corporaciones de seguridad.<\/p>\n<p>&#8220;Aqu\u00ed, en Garc\u00eda, a las ratas las cazamos; a los delincuentes los atrapamos y hacemos que la justicia les llegue. Por eso hoy los resultados hablan por s\u00ed solos&#8221;, afirm\u00f3.<\/p>\n<p>El presidente municipal destac\u00f3 que la estrategia de seguridad ha permitido reducir de manera hist\u00f3rica la incidencia delictiva.<\/p>\n<p>&#8220;Pasamos de registrar hasta 25 homicidios al mes en 2024 a cero homicidios durante junio de este a\u00f1o. Lo digo fuerte y claro: cero homicidios. En materia de seguridad no damos un paso atr\u00e1s; seguimos actuando con determinaci\u00f3n, inteligencia, tecnolog\u00eda y sin improvisaciones&#8221;, puntualiz\u00f3.<br \/>\nPor su parte, el secretario de Seguridad y Protecci\u00f3n Ciudadana, Guadalupe Salda\u00f1a Vargas, se\u00f1al\u00f3 que la incorporaci\u00f3n de esta infraestructura tecnol\u00f3gica fortalecer\u00e1 las acciones de vigilancia y prevenci\u00f3n del delito.<br \/>\n&#8220;Sumar tecnolog\u00eda a la protecci\u00f3n ciudadana es fundamental. Este tipo de herramientas fortalece la estrategia Escudo Garc\u00eda y consolida los esfuerzos que hemos venido realizando para reducir la criminalidad y brindar mayor seguridad a todas las familias del municipio&#8221;, expres\u00f3.<\/p>\n<p>En la inauguraci\u00f3n del Arco Carretero Inteligente acompa\u00f1aron al alcalde Manuel Guerra Cavazos la presidenta honoraria del DIF Municipal, Ana Paula R\u00edos Garza; el secretario de Seguridad y Protecci\u00f3n Ciudadana, Dr. Guadalupe Salda\u00f1a Vargas; el director de Polic\u00eda, Juan Guillermo Torres Falc\u00f3n; el director general delegado de Garc\u00eda, Roberto Escamilla; el secretario de Tesorer\u00eda, Felipe Adri\u00e1n Cadena; el secretario de la Oficina Ejecutiva del Alcalde, Dr. David Mart\u00ednez Valdez; el director general del C4 Inteligente, \u00c1ngel Adri\u00e1n Mu\u00f1oz Aguilar; y el comisionado general de Movilidad, Cultura Vial y Formaci\u00f3n Ciudadana, Dr. Ramiro Gonz\u00e1lez L\u00f3pez.<img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/mexpress.info\/index\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-11.48.29-AM.jpeg?resize=300%2C200\" alt=\"\" width=\"300\" height=\"200\" class=\"alignnone size-medium wp-image-141193\" srcset=\"https:\/\/i0.wp.com\/mexpress.info\/index\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-11.48.29-AM.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/mexpress.info\/index\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-11.48.29-AM.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mexpress.info\/index\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-11.48.29-AM.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conectado al C4 Inteligente, el nuevo sistema fortalece la vigilancia, el control vehicular y la capacidad de respuesta; el municipio pas\u00f3 de registrar hasta 25 homicidios mensuales en 2024 a cero durante junio de 2026. Garc\u00eda, Nuevo Le\u00f3n.\u2013 Como parte del fortalecimiento de la estrategia integral de seguridad &#8220;Escudo Garc\u00eda&#8221;, el alcalde Manuel Guerra Cavazos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":141194,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-141192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mexpress.info\/index\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-11.48.29-AM-1.jpeg?fit=1280%2C854&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/posts\/141192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/comments?post=141192"}],"version-history":[{"count":1,"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/posts\/141192\/revisions"}],"predecessor-version":[{"id":141195,"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/posts\/141192\/revisions\/141195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/media\/141194"}],"wp:attachment":[{"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/media?parent=141192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/categories?post=141192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mexpress.info\/index\/wp-json\/wp\/v2\/tags?post=141192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}